{"id":18995,"date":"2022-12-22T08:06:00","date_gmt":"2022-12-22T08:06:00","guid":{"rendered":"https:\/\/archivioturi.lavocedelpaese.info\/?p=18995"},"modified":"2023-01-29T08:08:17","modified_gmt":"2023-01-29T08:08:17","slug":"estorsioni-ai-cantieri-edilizi-e-traffico-di-stupefacenti-6-arresti","status":"publish","type":"post","link":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/2022\/12\/22\/estorsioni-ai-cantieri-edilizi-e-traffico-di-stupefacenti-6-arresti\/","title":{"rendered":"Estorsioni ai cantieri edilizi e traffico di stupefacenti, 6 arresti"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>I reati, aggravati dal metodo mafioso, sono stati commessi<br>nei Comuni di Turi, Bari, Casamassima e Locorotondo<\/strong><\/p>\n\n\n\n<p>I Carabinieri del Comando Provinciale di Bari hanno eseguito sei ordini di carcerazione, emessi dalla Procura Generale presso la Corte di Appello di Bari (ufficio esecuzioni penali), nei confronti di Battista Antonio (51enne), Kiwan Talal (49enne), Lopriore Alessandro (30enne), Carbonara Vito (38enne), Pala Antonio (44enne) e Surio Piero (49enne), destinatari di sentenze definitive di condanna, per gravi reati commessi tra il 2011 e il 2015, riconducibili alle dinamiche di riorganizzazione ed espansione del clan Di Cosola.<\/p>\n\n\n\n<p>L\u2019attivit\u00e0 investigativa, svolta dal Nucleo Investigativo dei Carabinieri e coordinata dalla Direzione Distrettuale Antimafia della Procura della Repubblica di Bari, ha consentito di ricostruire, oltre al traffico di stupefacenti, il sistema di estorsioni nel settore dell\u2019edilizia organizzato dal clan Di Cosola nei comuni di Ceglie del Campo, Valenzano, Capurso, Casamassima, Adelfia e Bitritto, che prevedeva l\u2019obbligo per gli imprenditori edili di consegnare denaro a titolo di protezione o, in alternativa, di acquistare il cemento prodotto da un\u2019impresa a loro collegata.<\/p>\n\n\n\n<p>Le condanne promanano dalla conclusione delle fasi processuali connesse all\u2019indagine Pilastro, avviata nel marzo del 2011 a seguito dell\u2019omicidio di Mizzi Giuseppe.<\/p>\n\n\n\n<p>Nel processo di primo grado nei confronti degli 80 imputati sono state emesse sentenze di condanna (con rito ordinario e rito abbreviato) ad una pena complessiva per circa 8 secoli di reclusione, ridotta a circa 4 secoli complessivi di reclusione nel giudizio di appello.<\/p>\n\n\n\n<p>Sopraggiunta l\u2019irrevocabilit\u00e0 delle sentenze, i Carabinieri hanno proceduto all\u2019esecuzione dei provvedimenti di carcerazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I reati, aggravati dal metodo mafioso, sono stati commessinei Comuni di Turi, Bari, Casamassima e Locorotondo I Carabinieri del Comando<\/p>\n","protected":false},"author":1,"featured_media":18996,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[8],"tags":[],"class_list":["post-18995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cronaca"],"_links":{"self":[{"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/18995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/comments?post=18995"}],"version-history":[{"count":1,"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/18995\/revisions"}],"predecessor-version":[{"id":18997,"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/posts\/18995\/revisions\/18997"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media\/18996"}],"wp:attachment":[{"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/media?parent=18995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/categories?post=18995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archivioturi.lavocedelpaese.info\/index.php\/wp-json\/wp\/v2\/tags?post=18995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}